{"id":32037,"date":"2026-05-13T07:17:06","date_gmt":"2026-05-13T04:17:06","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/trump-spricht-von-fake-news-iran-soll-noch-grosteil-seines-raketenarsenals-besitzen\/"},"modified":"2026-05-13T07:17:06","modified_gmt":"2026-05-13T04:17:06","slug":"trump-spricht-von-fake-news-iran-soll-noch-grosteil-seines-raketenarsenals-besitzen","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/trump-spricht-von-fake-news-iran-soll-noch-grosteil-seines-raketenarsenals-besitzen\/","title":{"rendered":"Trump spricht von &#8220;Fake News&#8221;: Iran soll noch Gro\u00dfteil seines Raketenarsenals besitzen"},"content":{"rendered":"<p class=\"caps\">Politik<\/p>\n<h2>Trump spricht von &quot;Fake News&quot;Iran soll noch Gro\u00dfteil seines Raketenarsenals besitzen<\/h2>\n<p>13.05.2026, 04:46 Uhr Artikel anh\u00f6ren(04:36 min)<audio src=\"https:\/\/mp3.n-tv.de\/2026\/05\/TTSART_30816103_20260513045105-radleg2.mp3\"><\/audio>00:00 \/ 04:36<\/p>\n<ul>\n<li>0.5x<\/li>\n<li>0.8x<\/li>\n<li>1.0x<\/li>\n<li>1.2x<\/li>\n<li>1.5x<\/li>\n<li>2.0x<\/li>\n<\/ul>\n<figure><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/img\/30816117\/1778646999\/Img_16_9\/1024\/A-symbolic-mockup-of-an-Iranian-missile-is-displayed-amid-a-ceasefire-between-U-S-and-Iran-in-Tehran-Iran-April-27-2026.webp\" alt=\"A-symbolic-mockup-of-an-Iranian-missile-is-displayed-amid-a-ceasefire-between-U-S-and-Iran-in-Tehran-Iran-April-27-2026\"\/><figcaption>Das ist nur eine Attrappe, doch Teheran soll auch noch \u00fcber reichlich echte Raketen verf\u00fcgen. (Foto: via REUTERS)<\/figcaption><\/figure>\n<p>Milit\u00e4risch sei der Iran besiegt, betont die US-Regierung immer wieder. Doch daran gibt es Zweifel: Laut US-Medienberichten sind Teherans Best\u00e4nde an Raketen und Abschussrampen noch lange nicht ersch\u00f6pft.<\/p>\n<p>Der Iran verf\u00fcgt laut US-Medien immer noch \u00fcber den Gro\u00dfteil seiner Best\u00e4nde an mobilen Abschussrampen und Raketen. Die &quot;New York Times&quot; berichtet \u00fcber Erkenntnisse von US-Geheimdiensten, wonach der Iran noch etwa 70 Prozent seiner mobilen Abschussrampen sowie rund 70 Prozent des Raketenarsenals habe, das er vor dem Krieg hatte. Die Zeitung beruft sich dabei auf Personen, die mit den Geheimdiensterkenntnissen von Anfang dieses Monats vertraut sind. Demnach habe der Iran auch wieder Zugang zum Gro\u00dfteil seiner unterirdischen Raketenlager, hei\u00dft es. <\/p>\n<p>Die &quot;Washington Post&quot; hatte bereits vergangene Woche unter Berufung auf eine US-Geheimdienstanalyse \u00e4hnliche Zahlen genannt. Der Iran verf\u00fcge noch \u00fcber etwa 75 Prozent seiner Vorkriegsbest\u00e4nde an mobilen Abschussrampen sowie etwa 70 Prozent seiner Raketen, zitierte die Zeitung einen US-Beamten. Dieser verwies demnach auch auf Hinweise, dass die iranische F\u00fchrung in der Lage gewesen sei, fast alle ihrer unterirdischen Lagerst\u00e4tten wieder in Betrieb zu nehmen, einige besch\u00e4digte Raketen zu reparieren sowie einige neue Raketen fertigzustellen. <\/p>\n<p><a href=\"https:\/\/www.n-tv.de\/politik\/Der-Iran-drueckt-die-Arterie-langsam-zu-id30811294.html\" rel=\"noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/logo_grey.svg\" alt=\"August-14-2023-Persian-Gulf-The-Strait-of-Hormuz-bottom-left-connects-the-Gulf-of-Oman-with-the-Persian-Gulf-in-this-photograph-from-the-International-Space-Station-as-it-orbited-262-miles-above-southwestern-Iran-In-the-right-foreground-is-the-Northrop-Grumman-Cygnus-space-freighter-and-one-of-its-cymbal-shaped-UltraFlex-solar-arrays-Credit-Image-NASA-Earth-ZUMA-Press-Wire-ZUMAPRESS\"\/>Wer zwinkert zuerst?&quot;Der Iran dr\u00fcckt die Arterie langsam zu&quot;<\/a><\/p>\n<p>Was einige hochrangige Beamte der &quot;New York Times&quot; zufolge besonders alarmiert: Es gibt offenbar Hinweise darauf, dass der Iran den Zugang zu den meisten seiner Raketenstellungen wiederhergestellt hat, die er entlang der Stra\u00dfe von Hormus unterh\u00e4lt. Aktuell herrscht im Iran-Krieg eine br\u00fcchige Waffenruhe, Verhandlungen um ein Kriegsende sind ins Stocken geraten.<\/p>\n<p>US-Pr\u00e4sident Donald Trump kritisierte zuletzt auf seiner Plattform Truth Social wieder einmal die mediale Berichterstattung \u00fcber den Iran-Krieg, ohne dabei konkrete Artikel zu nennen. &quot;Wenn die Fake News behaupten, dass der iranische Feind milit\u00e4risch gut gegen uns abschneidet, ist das praktisch VERRAT, insofern als es sich um eine derart falsche und sogar absurde Behauptung handelt.&quot; Sie unterst\u00fctzten den Feind, z\u00fcrnte der US-Pr\u00e4sident.<\/p>\n<h2>Sorge um US-Munitionsvorr\u00e4te<\/h2>\n<p>Die Berichte der &quot;New York Times&quot; und &quot;Washington Post&quot; stehen in starkem Kontrast zur Darstellung der US-Regierung, wonach der Iran durch den von Israel und den USA Ende Februar begonnenen Krieg milit\u00e4risch weitestgehend geschlagen sei. Sie fallen zudem in eine Zeit, in der die direkten und indirekten Kosten des Kriegs in den USA immer wieder Thema sind. <\/p>\n<p>Der US-Senator Mark Kelly etwa sagte j\u00fcngst, die Munitions- und Raketenvorr\u00e4te des US-Milit\u00e4rs seien stark aufgezehrt. Als Mitglied des Streitkr\u00e4fte-Ausschusses hatte das Pentagon den Demokraten \u00fcber bestimmte Munitionsarten informiert &#8211; nach Kellys Aussage geh\u00f6rten dazu etwa Angaben zu Raketen der Typen Tomahawk, ATACMS, SM-3 oder jene f\u00fcr die Flugabwehrsysteme vom Typ Patriot. <\/p>\n<p><a href=\"https:\/\/www.n-tv.de\/mediathek\/videos\/politik\/Schockierter-Senator-weckt-Zweifel-an-Trump-Aussage-Hegseth-reagiert-mit-Drohung-id30809202.html\" rel=\"noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/logo_grey.svg\" alt=\"Kelly_Munition\"\/>Kelly schl\u00e4gt Munitions-AlarmSchockierter Senator weckt Zweifel an Trump-Aussage<\/a><\/p>\n<p>Pentagon-Chef Pete Hegseth spielte Spekulationen \u00fcber stark aufgezehrte Munitions- und Raketenvorr\u00e4te herunter. &quot;Wir wissen genau, was wir haben. Wir verf\u00fcgen \u00fcber reichlich von dem, was wir brauchen&quot;, sagte er in einem Ausschuss des US-Repr\u00e4sentantenhauses. Die Debatte um die Vorr\u00e4te sei &quot;t\u00f6richterweise und wenig hilfreich \u00fcbertrieben&quot; worden, f\u00fchrte Hegseth weiter aus. Generalstabschef Dan Caine betonte, dass ihm die Regionalkommandos des US-Milit\u00e4rs ausreichende Munitionsvorr\u00e4te f\u00fcr die derzeitigen Missionen meldeten. Skeptiker sorgen sich jedoch weniger um aktuelle Eins\u00e4tze, sondern mehr um die Frage, ob die Munitionsvorr\u00e4te des US-Milit\u00e4rs auch f\u00fcr einen weiteren m\u00f6glichen Gro\u00dfkonflikt, etwa um Taiwan, reichen w\u00fcrden.<\/p>\n<p>Derweil steigen die Kosten des Milit\u00e4reinsatzes im Nahen Osten rasant: Bei einer Haushaltsanh\u00f6rung im US-Kongress bezifferte der Finanzchef des Verteidigungsministeriums, Jules Hurst, die Kosten inzwischen auf 29 Milliarden Dollar. Das sind rund vier Milliarden Dollar mehr als Verteidigungsminister Pete Hegseth Ende April als Sch\u00e4tzung angegeben hatte. Als Grund f\u00fcr den Anstieg nannte Hurst aktualisierte &quot;Kosten f\u00fcr die Reparatur und den Ersatz von Ausr\u00fcstung&quot;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politik Trump spricht von &quot;Fake News&quot;Iran soll noch Gro\u00dfteil seines Raketenarsenals besitzen 13.05.2026, 04:46 Uhr Artikel anh\u00f6ren(04:36 min)00:00 \/ 04:36 0.5x 0.8x 1.0x 1.2x 1.5x 2.0x Das ist nur eine<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-32037","post","type-post","status-publish","format-standard","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/32037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=32037"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/32037\/revisions"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=32037"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=32037"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=32037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}