{"id":31030,"date":"2025-12-03T09:36:20","date_gmt":"2025-12-03T06:36:20","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/hasstirade-im-kabinett-trump-beleidigt-somalier-als-mull\/"},"modified":"2025-12-03T09:36:20","modified_gmt":"2025-12-03T06:36:20","slug":"hasstirade-im-kabinett-trump-beleidigt-somalier-als-mull","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/hasstirade-im-kabinett-trump-beleidigt-somalier-als-mull\/","title":{"rendered":"Hasstirade im Kabinett: Trump beleidigt Somalier als &#8220;M\u00fcll&#8221;"},"content":{"rendered":"<p class=\"caps\">Politik<\/p>\n<h2>Hasstirade im KabinettTrump beleidigt Somalier als &quot;M\u00fcll&quot;<\/h2>\n<p>03.12.2025, 01:12 Uhr <\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/img\/30097771\/1764724490\/Img_16_9\/1024\/Trumps-Regierung-wirft-Maduro-vor-toedliche-Drogen-und-Gewalt-in-die-USA-zu-bringen.webp\" alt=\"Trumps-Regierung-wirft-Maduro-vor-toedliche-Drogen-und-Gewalt-in-die-USA-zu-bringen\"\/><figcaption>Seine j\u00fcngsten Attacken gegen Somalier wurden auch in der amerikanischen Presse als ungew\u00f6hnlich ausfallend gewertet. (Foto: Alex Brandon\/AP\/dpa)<\/figcaption><\/figure>\n<p>US-Pr\u00e4sident Trump stellt Migranten immer wieder pauschal als gef\u00e4hrliche Kriminelle dar und beleidigt sie rassistisch. Das neuste Opfer seiner verbalen Ausf\u00e4lle: Somalier. Am Ende einer langen Kabinettssitzung nutzt er besonders entmenschlichende Sprache.<\/p>\n<p>US-Pr\u00e4sident Donald Trump hat Somalia als miserables Land und Somalier als M\u00fcll bezeichnet. &quot;Ich will sie nicht in unserem Land haben. Ich bin ehrlich. Manche sagen vielleicht: &quot;Oh, das ist politisch nicht korrekt.&quot; Das ist mir egal. Ich will sie nicht in unserem Land haben&quot;, sagte Trump am Ende einer Kabinettssitzung. Die USA k\u00f6nnten den einen oder den anderen Weg einschlagen, &quot;und wir werden den falschen Weg einschlagen, wenn wir weiterhin M\u00fcll in unser Land lassen&quot;. <\/p>\n<p>Vergangene Woche hatte Trump bereits behauptet, Fl\u00fcchtlinge seien heute der Hauptgrund f\u00fcr gesellschaftliche Probleme in den USA und f\u00fchrte dann den Bundesstaat Minnesota als Beispiel an, der &quot;von Hunderttausenden Fl\u00fcchtlingen aus Somalia \u00fcbernommen&quot; worden sei. Zuvor hatte er bereits \u00f6ffentlichkeitswirksam das Ende eines Schutzprogramms f\u00fcr Somalier in Minnesota verk\u00fcndet, unter das aktuellen Statistiken zufolge blo\u00df ein paar Hundert Menschen fallen. <\/p>\n<p>Am Dienstag beschimpfte Trump ausdr\u00fccklich auch die somalischst\u00e4mmige demokratische Kongressabgeordneten Ilhan Omar aus Minnesota. &quot;Ilhan Omar ist M\u00fcll. Ihre Freunde sind M\u00fcll&quot;, w\u00fctete er. Mit seiner Tirade reagierte Trump auch auf einen riesigen Skandal im Bundesstaat Minnesota, bei dem mehrere Dutzend Somalier das Sozialsystem des Bundesstaates unter F\u00fchrung von Gouverneur Tim Walz um Hunderte Millionen Dollar betrogen haben sollen. <\/p>\n<p>Omar reagierte mit den Worten, Trumps &quot;Besessenheit&quot; mit ihrer Person sei unheimlich. &quot;Ich hoffe, er bekommt die Hilfe, die er dringend braucht&quot;, schrieb die Demokratin auf der Plattform X. Der somalischst\u00e4mmige Lokalpolitiker Jamal Osman aus Minnesota erkl\u00e4rte bei einer Pressekonferenz, wegen Trumps Rhetorik h\u00e4tten viele Familien Angst. Der Pr\u00e4sident sei rassistisch und islamophob, sagte Osman, betonte aber, man werde sich &quot;davon nicht spalten lassen&quot;.<\/p>\n<p><a href=\"https:\/\/www.n-tv.de\/politik\/Trumps-Migrations-Rhetorik-ist-ein-Jahrhundert-Rueckfall-id30082381.html\" rel=\"noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/logo_grey.svg\" alt=\"President-Donald-Trump-delivers-remarks-at-a-Veterans-Day-ceremony-at-the-Memorial-Amphitheater-at-Arlington-National-Cemetery-Tuesday-November-11-2025-in-Arlington-Virginia\"\/>Studie zeigt neue, alte H\u00e4rte Trumps Migrations-Rhetorik ist ein Jahrhundert-R\u00fcckfall<\/a><\/p>\n<p>Trump stellt Migranten immer wieder pauschal als gef\u00e4hrliche Kriminelle dar und beleidigt sie rassistisch. Er nutzt dazu auch entmenschlichende Sprache und sagte etwa, diese w\u00fcrden das &quot;Blut unseres Landes vergiften&quot;. Seine j\u00fcngsten Attacken gegen Somalier wurden auch in der amerikanischen Presse als ungew\u00f6hnlich ausfallend gewertet. Beweise f\u00fcr seine Thesen blieb Trump auch diesmal schuldig. <\/p>\n<p>In US-Medien wurde derweil \u00fcber bevorstehende Razzien der Einwanderungsbeh\u00f6rde ICE gegen somalische Migranten in den St\u00e4dten Minneapolis und St. Paul im Bundesstaat Minnesota spekuliert. Die &quot;New York Times&quot; berichtete, die Operation richte sich gegen Hunderte Somalier ohne notwendige Aufenthaltspapiere. In Minnesota leben nach Medienberichten \u00fcber 60.000 Menschen aus Somalia, die meisten legal. Es ist die gr\u00f6\u00dfte Gemeinschaft von Somaliern in den USA. Nach Angaben des Magazins Axios lag ihr Bev\u00f6lkerungsanteil 2023 im Bundesstaat bei 1,05 Prozent.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politik Hasstirade im KabinettTrump beleidigt Somalier als &quot;M\u00fcll&quot; 03.12.2025, 01:12 Uhr Seine j\u00fcngsten Attacken gegen Somalier wurden auch in der amerikanischen Presse als ungew\u00f6hnlich ausfallend gewertet. (Foto: Alex Brandon\/AP\/dpa) US-Pr\u00e4sident<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-31030","post","type-post","status-publish","format-standard","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/31030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=31030"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/31030\/revisions"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=31030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=31030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=31030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}