{"id":27503,"date":"2024-05-20T12:56:19","date_gmt":"2024-05-20T09:56:19","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/warten-auf-arbeitserlaubnis-begehrte-auslandische-arzte-scheitern-an-burokratie\/"},"modified":"2024-05-20T12:56:19","modified_gmt":"2024-05-20T09:56:19","slug":"warten-auf-arbeitserlaubnis-begehrte-auslandische-arzte-scheitern-an-burokratie","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/warten-auf-arbeitserlaubnis-begehrte-auslandische-arzte-scheitern-an-burokratie\/","title":{"rendered":"Warten auf Arbeitserlaubnis: Begehrte ausl\u00e4ndische \u00c4rzte scheitern an B\u00fcrokratie"},"content":{"rendered":"<p class=\"caps\">Panorama         \t\t                   \t\t               \t\t                    <\/p>\n<figure> \t\t                       \t\t                        <img decoding=\"async\" alt=\"Der mexikanische Arzt Jos\u00e9 Jim\u00e9nez hat Gl\u00fcck, er darf in der Geriatrischen Fachklinik Rheinhessen-Nahe behandeln. Viele seiner ausl\u00e4ndischen Kollegen und Kolleginnen m\u00fcssen dagegen weiter warten. \" src=\"https:\/\/apps-cloud.n-tv.de\/img\/24953703-1716192060000\/16-9\/750\/425268454.jpg\"\/><figcaption>\n<p>Der mexikanische Arzt Jos\u00e9 Jim\u00e9nez hat Gl\u00fcck, er darf in der Geriatrischen Fachklinik Rheinhessen-Nahe behandeln. Viele seiner ausl\u00e4ndischen Kollegen und Kolleginnen m\u00fcssen dagegen weiter warten.<\/p>\n<\/figcaption><\/figure>\n<p><strong>Deutschland fehlt es an \u00c4rzten. Besonders in l\u00e4ndlichen Regionen mangelt es an medizinischer Versorgung. Und das, obwohl Tausende ausl\u00e4ndische \u00c4rzte zuletzt ins Land kommen. Aber die haben mit der B\u00fcrokratie zu k\u00e4mpfen &#8211; und einem Vorgaben-Wirrwarr in den Bundesl\u00e4ndern. <\/strong><\/p>\n<p>Die Bewerberinnen und Bewerber kommen aus der T\u00fcrkei, aus Syrien, der Ukraine und vielen anderen L\u00e4ndern. Sie alle wollen als \u00c4rztin oder Arzt in Deutschland arbeiten. Viele Kommunen und Krankenh\u00e4usern sind dar\u00fcber froh. Regionaler \u00c4rztemangel rei\u00dft l\u00e4ngst L\u00fccken in die Versorgung. Doch vor dem Einsatz der ausl\u00e4ndischen Mediziner in deutschen Praxen, Versorgungszentren oder Kliniken stehen langwierige Verfahren. In den Beh\u00f6rden, die f\u00fcr Anerkennung und Arbeitserlaubnis zust\u00e4ndig sind, stauen sich derzeit viele Antr\u00e4ge &#8211; zum \u00c4rger von Betroffenen. Werden am Ende die Patientinnen und Patienten deshalb schlechter versorgt? Was k\u00f6nnte helfen?<\/p>\n<p>Ob im S\u00fcdschwarzwald oder an der Mecklenburgischen Seenplatte, im Taunus oder in Th\u00fcringen: Ausl\u00e4ndische \u00c4rztinnen und \u00c4rzte sind in vielen deutschen St\u00e4dten begehrt. Im badischen Bad S\u00e4ckingen zum Beispiel schien die Suche nach einem Nachfolger f\u00fcr die gyn\u00e4kologische Praxis im \u00f6rtlichen Medizinischen Versorgungszentrum (MVZ) schon erfolglos. Dabei wurde schon ein Arbeitsvertrag mit einem t\u00fcrkischen Bewerber geschlossen &#8211; doch die Zulassung lie\u00df auf sich warten. Medizinischen Fachangestellten wurde bereits gek\u00fcndigt. Nach bangen Wochen fand das MVZ laut &quot;Badischer Zeitung&quot; doch noch einen Gyn\u00e4kologen aus der Region. Unterdessen k\u00e4mpft in Aalen auf der Ostalb ein Mediziner aus Venezuela seit Monaten um seine Anerkennung, um als Hausarzt zu arbeiten.<\/p>\n<figure> <a href=\"https:\/\/www.n-tv.de\/panorama\/Patientenschuetzer-fordern-Qualitaetschecks-in-Praxen-article24922390.html\" rel=\"noreferrer noopener\" target=\"_blank\">      <img decoding=\"async\" alt=\"422310805.jpg\" src=\"https:\/\/apps-cloud.n-tv.de\/img\/24922392-1714967767000\/17-6\/1136\/422310805.jpg\"\/> <\/a> <\/figure>\n<p>   Panorama  06.05.24    Arbeit von \u00c4rzten auf Pr\u00fcfstand Patientensch\u00fctzer fordern Qualit\u00e4tschecks in Praxen    <\/p>\n<p>Im th\u00fcringischen Eisenach wartet eine Ukrainerin, die bereits seit 27 Jahren als Kinder\u00e4rztin in ihrer Heimat gearbeitet hatte, auf die Anerkennung ihres Studienabschlusses. &quot;Schade, dass es sehr, sehr lange dauert&quot;, sagte sie dem MDR. F\u00fcr sie blieb in der Kinderstation zun\u00e4chst nur der Einsatz als Hospitantin. Im hessischen Bad Schwalbach wuchs unterdessen bei einem kolumbianischen Arzt die Wut: Einen Arbeitsvertrag bei einer Klinik hatte er schon &#8211; nur die beantragte Approbation lie\u00df auf sich warten, und die zust\u00e4ndige Landesbeh\u00f6rde erreichte er erst gar nicht f\u00fcr Nachfragen, wie er dem Hessischen Rundfunk sagte. <\/p>\n<h2>Immer mehr ausl\u00e4ndische \u00c4rzte<\/h2>\n<p>Dabei ist die Zahl ausl\u00e4ndischen \u00c4rztinnen und \u00c4rzte vergangenes Jahr auf eine neue H\u00f6chstmarke gestiegen &#8211; auf knapp 64 000. Nach einer verlangsamten Zuwanderung w\u00e4hrend der Corona-Pandemie steigt ihr Zuzug wieder, wie die Vizepr\u00e4sidentin der Bundes\u00e4rztekammer, Ellen Lundershausen, sagt. &quot;Die Einwanderung von ausl\u00e4ndischen \u00c4rztinnen und \u00c4rzten wird sich voraussichtlich auch in den kommenden Jahren fortsetzen.&quot; Syrien lag bei den Herkunftsl\u00e4ndern im Jahr 2023 vorn (6120 \u00c4rztinnen und \u00c4rzte), gefolgt von Rum\u00e4nien (4668), \u00d6sterreich (2993), Griechenland (2943), Russland (2941) und der T\u00fcrkei (2628). &quot;Seit rund eineinhalb Jahren erleben wir einen gro\u00dfen Anstieg aus der T\u00fcrkei&quot;, berichtet die Leiterin der Gutachtenstelle f\u00fcr Gesundheitsberufe, Carola D\u00f6rfler. Die verbreitete Unzufriedenheit mit der politischen und wirtschaftlichen Lage in dem Land k\u00f6nne der Grund sein. Seit rund einem Jahr steigen auch die Bewerberzahlen ukrainischer Kriegsfl\u00fcchtlinge.<\/p>\n<figure> <a href=\"https:\/\/www.n-tv.de\/politik\/Lauterbachs-Hausaerzte-Alarm-kommt-schlecht-an-article24875711.html\" rel=\"noreferrer noopener\" target=\"_blank\">      <img decoding=\"async\" alt=\"214242650.jpg\" src=\"https:\/\/apps-cloud.n-tv.de\/img\/24875720-1713212078000\/17-6\/1136\/214242650.jpg\"\/> <\/a> <\/figure>\n<p>   Politik  16.04.24    &quot;Nicht mit Zahlen rumwerfen&quot; Lauterbachs Haus\u00e4rzte-Alarm kommt schlecht an    <\/p>\n<p>In D\u00f6rflers Einrichtung \u00fcberpr\u00fcfen unter anderem \u00c4rzte und Therapeuten sowie Dokumentare und Dokumentarinnen im Auftrag der Bundesl\u00e4nder die eingereichten Abschl\u00fcsse und Dokumente auf ihre Gleichwertigkeit in Deutschland. In vielen Regionen wird auch einiges f\u00fcr den Zuzug ausl\u00e4ndischer \u00c4rzte getan. So gewann das Klinikum in Neubrandenburg mit einem Programm der Agentur f\u00fcr Arbeit elf Jung-Medizinerinnen und Mediziner aus Mexiko zur weiteren Qualifikation. Baden-W\u00fcrttemberg will die Verfahren per geb\u00fcndelter Beh\u00f6rden-Anlaufstelle erleichtern, Bayern auch mit k\u00fcnstlicher Intelligenz. <\/p>\n<h2>Jedes Bundesland tickt anders<\/h2>\n<p>Doch statt Freude herrscht vielerorts Frust. &quot;Der Anstieg der Bewerberzahlen aus der T\u00fcrkei und der Ukraine hat zu einem Stau gef\u00fchrt&quot;, r\u00e4umt Gutachtenstellen-Leiterin D\u00f6rfler ein. &quot;Die Personalausstattung der Beh\u00f6rden hinkt der Entwicklung hinterher.&quot; Die Dauer der Gleichwertigkeitspr\u00fcfung in ihrem Haus: ein halbes Jahr, acht Monate oder vereinzelt bis zu einem Jahr. \u00c4rztekammer-Vizepr\u00e4sidentin Lundershausen sagt: &quot;Zweifelsohne besteht aufgrund des komplexen Anerkennungsverfahrens die Gefahr langer Wartezeiten oder H\u00e4ngepartien.&quot; H\u00e4ufig erschienen die Abl\u00e4ufe der verschiedenen Beh\u00f6rden widerspr\u00fcchlich.<\/p>\n<p>Von den praktischen Problemen kann Elitsa Seidel ein Lied singen. Mit ihrer Mainzer Agentur &quot;inmed personal&quot; hilft sie Bewerberinnen und Bewerbern bei der Anerkennung. Seidel beklagt die unterschiedlichen Anforderungen in den Bundesl\u00e4ndern &#8211; von der Form der Beglaubigung der Unterlagen bis hin zur Wartezeit auf die ebenfalls n\u00f6tige Fachsprachpr\u00fcfung. &quot;Das dauert zwei Monate bis zu einem halben Jahr.&quot; Manche Bewerberinnen und Bewerber gerieten in einen Teufelskreis. &quot;Die Kliniken brauchen Planungssicherheit und akzeptieren daher nur voll anerkannte Bewerber&quot;, so Seidel. Viele Approbationsbeh\u00f6rden verlangten aber einen Einstellungsnachweis, bevor sie den Antrag \u00fcberhaupt bearbeiten &#8211; vor allem, wenn die \u00c4rzte noch keinen deutschen Wohnsitz haben.<\/p>\n<h2>Die Zeugnisse reichen oft nicht aus<\/h2>\n<p>&quot;Oft erscheint alles ganz einfach: Eine Klinik oder ein MVZ will einen Arzt einstellen, der Arzt will eingestellt werden&quot;, sagt Agentur-Chefin Seidel. F\u00fcr die Bewerber entwickelt sich das Herbeischaffen aller Dokumente und der Vergleich mit den deutschen Anforderungen trotzdem nicht selten zum Drama. Seidel erl\u00e4utert, es k\u00f6nne schnell zwei, drei Monate l\u00e4nger dauern, wenn der Anerkennungsbeh\u00f6rde ein Zeugnis fehlt. &quot;Die Anerkennungsverfahren ziehen sich in die L\u00e4nge, wenn die Unterlagen nicht vollst\u00e4ndig vorliegen oder die Personalressourcen in den Beh\u00f6rden eine schnelle Pr\u00fcfung nicht zulassen&quot;, meint Lundershausen. &quot;Oft liegt es auch nicht an den Beh\u00f6rden, etwa wenn Dokumente nachgereicht werden&quot;, sagt D\u00f6rfler. Sie findet: Es k\u00f6nnte alles auch einfacher sein. Denn heute m\u00fcssen Antragsteller ihre Dokumente auf jeden Fall erst auf Gleichwertigkeit in Deutschland pr\u00fcfen lassen. Aber bei rund drei von vier Bewerbern reichen die Zeugnisse nicht. Sie m\u00fcssen in eine pers\u00f6nliche Arztpr\u00fcfung, die Kenntnispr\u00fcfung. <\/p>\n<p>  <strong>Mehr zum Thema<\/strong>    Neuverg\u00fctung soll nicht belasten Lauterbach: Keine h\u00f6heren Beitr\u00e4ge trotz Haus\u00e4rzte-Reform       &quot;Pickel am Po&quot; k\u00f6nnte kosten Verband fordert Notfall-Geb\u00fchr f\u00fcr Eltern bei unn\u00f6tigen F\u00e4llen       Gegen den Haus\u00e4rztemangel Reform des Medizinstudiums soll mehr \u00c4rzte in Praxen bringen    <\/p>\n<p>D\u00f6rfler schl\u00e4gt vor, dass die Betroffenen k\u00fcnftig vorher w\u00e4hlen d\u00fcrfen, ob sie ihre Dokumente \u00fcberpr\u00fcfen lassen. Bei mangelnder Erfolgsaussicht sollten sie sich gleich auf die Kenntnispr\u00fcfung konzentrieren k\u00f6nnen. D\u00f6rfler wirbt f\u00fcr die Idee: &quot;Es w\u00fcrde eine Menge Beh\u00f6rdenarbeit einsparen.&quot;<\/p>\n<h2>Lauterbach beklagt Einsparungen<\/h2>\n<p>Die Expertinnen sind sich einig: Die Zusammenarbeit der Beh\u00f6rden sei ausbauf\u00e4hig, so \u00c4rztekammer-Vize Lundershausen. Seidel: &quot;Es w\u00e4re wichtig, b\u00fcrokratische H\u00fcrden zu senken &#8211; im Gegensatz zu den sprachlichen und fachlichen Voraussetzungen, die einfach gegeben sein m\u00fcssen.&quot; Doch sind die fachlichen Qualifikationen f\u00fcr den Einsatz an den Patienten auch immer gegeben? &quot;Wir haben es mit einem sehr heterogenen Feld an Bewerbern und Bewerberinnen zu tun&quot;, mahnt der Leiter des Instituts f\u00fcr Ausbildung und Studienangelegenheiten an der Medizin-Fakult\u00e4t in M\u00fcnster, Bernhard Marschall. &quot;Dass jemand sehr versierte Erfahrungen mitbringt, ist sehr selten.&quot; Zum Schutz der Patientinnen und Patienten seien gr\u00fcndliche Anerkennungsverfahren unabdingbar.<\/p>\n<p>Bundesgesundheitsminister Karl Lauterbach r\u00e4umte auf dem \u00c4rztetag im Mai ein, \u00fcber Jahre seien auch aus Spargr\u00fcnden zu wenig \u00c4rztinnen und \u00c4rzte hierzulande ausgebildet worden. Stattdessen hole Deutschland immer mehr ausl\u00e4ndische Mediziner ins Land. &quot;Das ist nicht ethisch und kann so nicht weitergehen.&quot; <\/p>\n<p>Marschall weist auch auf eine anderes Ungleichgewicht hin: Wegen ungleichm\u00e4\u00dfiger Verteilung der insgesamt 428.000 \u00c4rztinnen und \u00c4rzte in Deutschland landeten die ausl\u00e4ndischen Mediziner oft in strukturschwachen Regionen. Dort, wo die Arbeit und das Leben den hier ausgebildeten \u00c4rzten weniger attraktiv erscheine &#8211; und Patientinnen und Patienten sich wom\u00f6glich schon abgeh\u00e4ngt f\u00fchlten.<\/p>\n<p>Quelle: ntv.de, Basil Wegener, dpa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Panorama Der mexikanische Arzt Jos\u00e9 Jim\u00e9nez hat Gl\u00fcck, er darf in der Geriatrischen Fachklinik Rheinhessen-Nahe behandeln. Viele seiner ausl\u00e4ndischen Kollegen und Kolleginnen m\u00fcssen dagegen weiter warten. Deutschland fehlt es an<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27503","post","type-post","status-publish","format-standard","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/27503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=27503"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/27503\/revisions"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=27503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=27503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=27503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}