{"id":18610,"date":"2023-03-01T05:18:35","date_gmt":"2023-03-01T02:18:35","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gesunde-ernahrung-diaten-und-intuitives-essen-immer-nur-nein-sagen-ist-schwierig\/"},"modified":"2023-03-01T05:18:35","modified_gmt":"2023-03-01T02:18:35","slug":"gesunde-ernahrung-diaten-und-intuitives-essen-immer-nur-nein-sagen-ist-schwierig","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gesunde-ernahrung-diaten-und-intuitives-essen-immer-nur-nein-sagen-ist-schwierig\/","title":{"rendered":"Gesunde Ern\u00e4hrung, Di\u00e4ten und Intuitives Essen: \u00bbImmer nur nein sagen, ist schwierig\u00ab"},"content":{"rendered":"<p class=\"caps\">Warum essen wir oft zu viel, zu fett, zu s\u00fc\u00df? Forscherin Katja Kr\u00f6ller erkl\u00e4rt, wie wir unsere Gewohnheiten \u00e4ndern, was ein Zuckerwerbeverbot f\u00fcr Kinder bringt und was Eltern in der Erziehung besser machen k\u00f6nnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Warum essen wir oft zu viel, zu fett, zu s\u00fc\u00df? Forscherin Katja Kr\u00f6ller erkl\u00e4rt, wie wir unsere Gewohnheiten \u00e4ndern, was ein Zuckerwerbeverbot f\u00fcr Kinder bringt und was Eltern in der<\/p>\n","protected":false},"author":1,"featured_media":18611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-18610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/18610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=18610"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/18610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/18611"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=18610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=18610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=18610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}