{"id":17438,"date":"2023-01-09T04:47:27","date_gmt":"2023-01-09T01:47:27","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/brasilia-polizei-bringt-regierungsgebaude-unter-kontrolle\/"},"modified":"2023-01-09T04:47:27","modified_gmt":"2023-01-09T01:47:27","slug":"brasilia-polizei-bringt-regierungsgebaude-unter-kontrolle","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/brasilia-polizei-bringt-regierungsgebaude-unter-kontrolle\/","title":{"rendered":"Bras\u00edlia: Polizei bringt Regierungsgeb\u00e4ude unter Kontrolle"},"content":{"rendered":"<p class=\"caps\">Spezialkr\u00e4fte konnten die drei Geb\u00e4ude r\u00e4umen, nachdem Demonstranten sich gewaltsam Eintritt verschafft hatten. Etwa 150 Bolsonaro-Anh\u00e4nger wurden festgenommen.  <\/p>\n<p>In der brasilianischen Hauptstadt Bras\u00edlia hat die Polizei wenige Stunden nach der Erst\u00fcrmung des Kongresses durch Anh\u00e4nger des rechtsextremen Ex-Pr\u00e4sidenten Jair Bolsonaro wieder die Kontrolle \u00fcber das Parlamentsgeb\u00e4ude \u00fcbernommen. Die Eins\u00e4tze zur R\u00e4umung des Pr\u00e4sidentenpalastes und des Obersten Gerichts dauerten am Sonntagabend an, wie Journalisten der Nachrichtenagentur AFP berichteten. Brasilianischen Medien zufolge wurden bis jetzt mindestens 150 Bolsonaro-Anh\u00e4nger festgenommen.<\/p>\n<h3>Polizei setzte Wasserwerfer ein<\/h3>\n<p>Gegen Einbruch der Dunkelheit schienen die Sicherheitskr\u00e4fte in der brasilianischen Hauptstadt die Situation allgemein nach und nach wieder unter Kontrolle zu bringen. Sie hielten Demonstranten mit Wasserwerfern auf Abstand. Dutzende Bolsonaro-Anh\u00e4nger verharrten aber vor Ort, die Lage blieb weiterhin un\u00fcbersichtlich.<\/p>\n<p>Auf Bildern des Fernsehsenders CNN Brasil war zu sehen, wie in Gelb und Gr\u00fcn gekleidete Bolsonaro-Anh\u00e4nger mit hinter dem R\u00fccken verschr\u00e4nkten Armen von Polizisten begleitet der Reihe nach die Rampe des Pr\u00e4sidentenpalastes Planalto heruntergingen. Ein Bus mit zuvor festgenommenen Demonstranten fuhr demnach in Richtung einer Polizeistation ab. Die Polizei des brasilianischen Senats erkl\u00e4rte, sie habe innerhalb der Kongresskammer 30 Menschen festgenommen.<\/p>\n<h3>Vandalen zertr\u00fcmmerten T\u00fcren und Fenster<\/h3>\n<p>Radikale Unterst\u00fctzer Bolsonaros waren am Nachmittag gewaltsam in den Kongress eingedrungen. Sie \u00fcberwanden Polizeiabsperrungen und gelangten in das Kongressgeb\u00e4ude, wie auf Videos zu sehen war, die in Online-Netzwerken verbreitet wurden. Dabei zertr\u00fcmmerten sie T\u00fcren und Fenster und str\u00f6mten dann in gro\u00dfer Zahl in das Parlamentsgeb\u00e4ude. Zudem st\u00fcrmten sie den nahegelegenen Pr\u00e4sidentenpalast und das Oberste Gericht.<\/p>\n<h3>Lula droht mit voller H\u00e4rte des Gesetzes<\/h3>\n<p>Der brasilianische Pr\u00e4sident Luiz In\u00e1cio Lula da Silva, der sich am Sonntag in der s\u00fcd\u00f6stlichen Stadt Araraquara aufhielt, sprach von einem Angriff \u00bbfaschistischer Vandalen\u00ab. Lula unterzeichnete ein Dekret, das den Bundesbeh\u00f6rden Sonderbefugnisse zur Wiederherstellung der Sicherheit in Bras\u00edlia einr\u00e4umt. \u00bbWir werden herausfinden, wer diese Vandalen sind, und sie werden mit der ganzen H\u00e4rte des Gesetzes bestraft werden\u00ab, sagte er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spezialkr\u00e4fte konnten die drei Geb\u00e4ude r\u00e4umen, nachdem Demonstranten sich gewaltsam Eintritt verschafft hatten. Etwa 150 Bolsonaro-Anh\u00e4nger wurden festgenommen. In der brasilianischen Hauptstadt Bras\u00edlia hat die Polizei wenige Stunden nach der<\/p>\n","protected":false},"author":1,"featured_media":17439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17438"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17439"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}