{"id":17420,"date":"2023-01-08T09:54:43","date_gmt":"2023-01-08T06:54:43","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/richtungsstreit-im-vatikan-papst-franziskus-allein-zu-haus\/"},"modified":"2023-01-08T09:54:43","modified_gmt":"2023-01-08T06:54:43","slug":"richtungsstreit-im-vatikan-papst-franziskus-allein-zu-haus","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/richtungsstreit-im-vatikan-papst-franziskus-allein-zu-haus\/","title":{"rendered":"Richtungsstreit im Vatikan: Papst Franziskus allein zu Haus"},"content":{"rendered":"<p class=\"caps\">W\u00e4hrend Konservative Benedikt XVI. als gro\u00dfen Denker feiern und heiligsprechen wollen, fehlt Franziskus ein klarer Kurs: Soll er sich auf die Seite der Traditionalisten schlagen \u2013 oder den Progressiven folgen?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrend Konservative Benedikt XVI. als gro\u00dfen Denker feiern und heiligsprechen wollen, fehlt Franziskus ein klarer Kurs: Soll er sich auf die Seite der Traditionalisten schlagen \u2013 oder den Progressiven folgen?<\/p>\n","protected":false},"author":1,"featured_media":17421,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17420"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17421"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}