{"id":17330,"date":"2023-01-04T10:47:40","date_gmt":"2023-01-04T07:47:40","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/energie-und-strompreise-debatte-um-atomkraftwerke-die-zweite\/"},"modified":"2023-01-04T10:47:40","modified_gmt":"2023-01-04T07:47:40","slug":"energie-und-strompreise-debatte-um-atomkraftwerke-die-zweite","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/energie-und-strompreise-debatte-um-atomkraftwerke-die-zweite\/","title":{"rendered":"Energie und Strompreise: Debatte um Atomkraftwerke, die Zweite"},"content":{"rendered":"<p class=\"caps\">Bis April sollen die Kernkraftwerke weiterlaufen \u2013 l\u00e4nger als geplant. Doch der FDP geht der m\u00fchsam ausverhandelte Deal nicht weit genug, auch Fachleute empfehlen den Kauf neuer Brennst\u00e4be. Lohnt sich das wirklich?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bis April sollen die Kernkraftwerke weiterlaufen \u2013 l\u00e4nger als geplant. Doch der FDP geht der m\u00fchsam ausverhandelte Deal nicht weit genug, auch Fachleute empfehlen den Kauf neuer Brennst\u00e4be. Lohnt sich<\/p>\n","protected":false},"author":1,"featured_media":17331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17330"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17331"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}