{"id":17322,"date":"2023-01-04T02:26:36","date_gmt":"2023-01-03T23:26:36","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/usa-kevin-mccarthy-scheitert-bei-wahl-zum-sprecher-des-reprasentantenhauses-auch-in-runde-drei\/"},"modified":"2023-01-04T02:26:36","modified_gmt":"2023-01-03T23:26:36","slug":"usa-kevin-mccarthy-scheitert-bei-wahl-zum-sprecher-des-reprasentantenhauses-auch-in-runde-drei","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/usa-kevin-mccarthy-scheitert-bei-wahl-zum-sprecher-des-reprasentantenhauses-auch-in-runde-drei\/","title":{"rendered":"USA: Kevin McCarthy scheitert bei Wahl zum Sprecher des Repr\u00e4sentantenhauses auch in Runde drei"},"content":{"rendered":"<p class=\"caps\">Der Machtkampf innerhalb der republikanischen Partei geht weiter: Auch beim dritten Wahlgang zum Vorsitz im US-Repr\u00e4sentantenhaus kann Kevin McCarthy nicht die n\u00f6tigen Stimmen hinter sich vereinen. Die n\u00e4chste Abstimmung erfolgt am Mittwoch.  <\/p>\n<p>In dem erbitterten Machtkampf der Republikaner um den Vorsitz im US-Repr\u00e4sentantenhaus hat auch der dritte Wahlgang keine Entscheidung gebracht. Nachdem der Republikaner Kevin McCarthy bei der Abstimmung im ersten Anlauf bereits eine historische Schlappe erlitten hatte, kam er in der konstituierenden Sitzung der Parlamentskammer auch in Runde zwei nicht auf die n\u00f6tige Mehrheit. Nun musste er sich auch in Runde drei dem Votum beugen. Die n\u00e4chste Abstimmung wird am Mittwoch erfolgen.<\/p>\n<p>Im ersten Wahlgang hatten sich 19 Parteikollegen gegen McCarthy aufgelehnt, verweigerten ihm die Unterst\u00fctzung und gaben anderen Kandidaten ihre Stimme. Nun stimmten bei der zweiten m\u00fcndlichen Abstimmungen wieder 19 Kollegen nicht f\u00fcr den 57-J\u00e4hrigen. Die Stimmen gingen stattdessen allesamt an den republikanischen Abgeordneten Jim Jordan. Dieser hatte zuvor McCarthy f\u00fcr den zweiten Wahlgang nominiert und seinen Parteikollegen ins Gewissen geredet, die Reihen zu schlie\u00dfen.<\/p>\n<p>Allerdings holte direkt im Anschluss einer der h\u00e4rtesten Gegner McCarthys, der Parlamentarier Matt Gaetz, zum Schlag aus und nominierte Jordan. Vielleicht sei es besser, jemanden zu w\u00e4hlen, der den Posten nicht so verzweifelt wolle, sagte Gaetz. Jordan habe schon in der kurzen Nominierungsansprache f\u00fcr McCarthy mehr Zukunftsvisionen aufgezeigt als von diesem je zu h\u00f6ren gewesen sei. Jordan ist ein Getreuer von Ex-Pr\u00e4sident Donald Trump.<\/p>\n<p>In der dritten Runde folgte das Abstimmungsverhalten der Abtr\u00fcnnigen dem gleichen Muster: Mehrere Parteikollegen verweigerten McCarthy erneut ihre Unterst\u00fctzung und stimmten stattdessen f\u00fcr den republikanischen Abgeordneten Jim Jordan.<\/p>\n<p>F\u00fcr McCarthy ist das eine \u00f6ffentliche Blo\u00dfstellung \u2013 sie zeigt auch die Zerrissenheit der Republikaner  zwischen jenen Parteimitgliedern, die wie Ex-Pr\u00e4sident Trump die Partei weiter nach rechts r\u00fccken wollen, und einem eher moderaten Fl\u00fcgel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Machtkampf innerhalb der republikanischen Partei geht weiter: Auch beim dritten Wahlgang zum Vorsitz im US-Repr\u00e4sentantenhaus kann Kevin McCarthy nicht die n\u00f6tigen Stimmen hinter sich vereinen. Die n\u00e4chste Abstimmung erfolgt<\/p>\n","protected":false},"author":1,"featured_media":17323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17322"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17323"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}