{"id":17282,"date":"2023-01-02T08:19:02","date_gmt":"2023-01-02T05:19:02","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-montag-2-januar\/"},"modified":"2023-01-02T08:19:02","modified_gmt":"2023-01-02T05:19:02","slug":"news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-montag-2-januar","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-montag-2-januar\/","title":{"rendered":"News zum Russland-Ukraine-Krieg: Das geschah in der Nacht zu Montag (2. Januar)"},"content":{"rendered":"<p class=\"caps\">Die russische Armee hat erneut Luftangriffe auf Kiew geflogen, Drohnentr\u00fcmmer verletzten einen jungen Mann. Und: Pr\u00e4sident Selenskyj nennt den Gegner \u00bberb\u00e4rmliche Terroristen\u00ab. Die wichtigsten Entwicklungen.  <\/p>\n<h3><strong>Was in den vergangenen Stunden geschah<\/strong><\/h3>\n<p>Russland hat die ukrainische Hauptstadt Kiew die zweite Nacht in Folge unter Beschuss genommen. Kurz vor Mitternacht wurde f\u00fcr Kiew und den gr\u00f6\u00dften Teil der Ostukraine erneut Luftalarm ausgel\u00f6st. Der Gouverneur der Region Kiew, Oleksiy Kuleba, teilte bei Telegramm mit, der Feind nehme gezielt kritische Infrastruktur bei seinen Drohnenangriffen ins Visier. Er erw\u00e4hnte explizit, dass es sich um Drohen aus iranischer Herstellung handele.<\/p>\n<p>Ein 19-j\u00e4hriger Mann wurde in ein Krankenhaus im Kiewer Stadtteil Desnianskij gebracht, nachdem Drohnentr\u00fcmmer ein Geb\u00e4ude getroffen h\u00e4tten. Dies teilte B\u00fcrgermeister Vitali Klitschko am Montag auf Telegram mit. Auch ein Berater des ukrainischen Pr\u00e4sidenten Wolodymyr Selenskyj sprach von Drohnentr\u00fcmmern, die eine Stra\u00dfe im bev\u00f6lkerungsreichsten Bezirk Desnianskij im Nordosten Kiews getroffen und ein danebenstehendes Geb\u00e4ude besch\u00e4digt h\u00e4tten.<\/p>\n<p>Das Milit\u00e4rkommando der Ukraine im Osten des Landes teilte mit, dass Luftabwehrsysteme in den fr\u00fchen Morgenstunden des Montags neun iranische Shahed-Drohnen \u00fcber den Regionen Dnipropetrowsk und Saporischschja zerst\u00f6rt h\u00e4tten.<\/p>\n<h3><strong>Das sagt Kiew<\/strong><\/h3>\n<p>Die Armeef\u00fchrung erkl\u00e4rte zudem, \u00bbdie russischen Besatzer\u00ab h\u00e4tten \u00bb16 Mal mit Mehrfachraketenwerfern geschossen\u00ab. Diese Angriffe richteten sich demnach insbesondere gegen das Kinderkrankenhaus in der s\u00fcdukrainischen Stadt Cherson.<\/p>\n<p>Pr\u00e4sident Selenskyj verurteilte die j\u00fcngsten russischen Drohnenangriffe auf St\u00e4dte seines Landes in der Neujahrsnacht mit scharfen Worten. \u00bbDie russischen Terroristen waren bereits erb\u00e4rmlich und sind auch so ins neue Jahr gestartet\u00ab, sagte Selenskyj am Sonntag in seiner t\u00e4glichen Videoansprache. Diese Angriffe k\u00f6nnten den Ukrainern nichts anhaben. \u00bbUnser Zusammengeh\u00f6rigkeitsgef\u00fchl, unsere Authentizit\u00e4t, das Leben selbst \u2013 all das steht so sehr im Kontrast zu der Angst, die in Russland vorherrscht.\u00ab<\/p>\n<p>Das russische Milit\u00e4r habe sp\u00fcrbar Angst, so Selenskyj. \u00bbUnd sie haben zu Recht Angst, denn sie werden verlieren.\u00ab Selbst mit Drohnen und Raketen k\u00e4men die russischen Milit\u00e4rs nicht weit. \u00bbWeil wir zusammenhalten.\u00ab Die russische Seite dagegen werde nur von Angst zusammengehalten, argumentierte er.<\/p>\n<p>Das russische Milit\u00e4r hatte in der Neujahrsnacht eine Welle sogenannter Kamikazedrohnen in Richtung ukrainischer St\u00e4dte gestartet. Die unter anderem auf die Hauptstadt Kiew und die ostukrainische Gro\u00dfstadt Charkiw gerichteten Schahed-Drohnen aus iranischer Produktion wurden nach Angaben aus Kiew von der ukrainischen Flugabwehr noch vor Erreichen ihrer Ziele abgeschossen. Insgesamt seien 45 Drohnen zerst\u00f6rt worden, teilte Selenskyj mit.<\/p>\n<p>Russland greift seit Wochen mit Marschflugk\u00f6rpern, Raketen und Drohnen gezielt das ukrainische Energienetz an. Die bisher angerichteten schweren Sch\u00e4den haben zu massiven Ausf\u00e4llen in der Wasser- und Stromversorgung gef\u00fchrt. Russland will mit dieser Taktik die Zivilbev\u00f6lkerung der Ukraine im Winter unter Druck setzen.<\/p>\n<h3><strong>Das sagt Moskau<\/strong><\/h3>\n<p>Russischen Angaben zufolge hatte die Ukraine zuvor in der Silvesternacht die Stadt Makiwka und andere Orte in den von Moskau kontrollierten Teilen der Region Donezk beschossen. Den Berichten zufolge wurde ein Milit\u00e4rquartier getroffen, wobei mehrere Menschen get\u00f6tet wurden. Mindestens 25 Raketen seien auf die Region abgefeuert worden, teilte die von Moskau eingesetzte Verwaltung in der Region Donezk mit.<\/p>\n<p>Die staatliche russische Nachrichtenagentur TASS zitierte die Verwaltung mit den Worten, dass in der Stadt Makiwka bei einer Reihe von Besch\u00fcssen mit Himars-Raketen (High Mobility Artillery Rocket System) mindestens 15 Menschen verletzt worden seien. Es habe einen Angriff auf eine Berufsschule gegeben, die als Quartier f\u00fcr milit\u00e4risches Personal diente, erkl\u00e4rte Daniil Bezsonow, Informationsminister der selbst ernannten \u00bbVolksrepublik Donezk\u00ab. Der Angriff habe sich am Neujahrstag zwei Minuten nach Mitternacht ereignet.<\/p>\n<h3><strong>Internationale Reaktionen<\/strong><\/h3>\n<p>Das Interesse russischer Geheimdienste an Deutschland nimmt nach Einsch\u00e4tzung des Verfassungsschutzes weiter zu, je l\u00e4nger der Krieg in der Ukraine andauert. \u00bbDas Aufkl\u00e4rungsinteresse Russlands hier in Deutschland ist nicht nur ungebrochen, sondern nimmt auch zu, je weiter sich die Auswirkungen des Krieges fortsetzen\u00ab, sagte der Pr\u00e4sident des Bundesamtes f\u00fcr Verfassungsschutz, Thomas Haldenwang, der Nachrichtenagentur dpa.<\/p>\n<p>\u00bbWie real die Gefahr russischer Spionage ist, zeigt auch der aktuelle Fall\u00ab, sagte Haldenwang mit Blick auf den kurz vor Weihnachten festgenommenen mutma\u00dflichen Doppelagenten beim Bundesnachrichtendienst (BND). Um die Ermittlungen nicht zu gef\u00e4hrden, wolle er sich, ebenso wie BND-Chef Bruno Kahl, nicht zu Einzelheiten \u00e4u\u00dfern. Der Festgenommene steht im Verdacht, geheime Informationen an einen russischen Nachrichtendienst gegeben zu haben.<\/p>\n<p>Haldenwang sagte, er erwarte, dass Moskau versuchen werden, die Aufkl\u00e4rungsm\u00f6glichkeiten, die durch die Ausweisung von 40 Agenten verloren gegangen seien, zu kompensieren: entweder durch mehr \u00bbreisende Agenten\u00ab oder durch andere Tarnungen. Um eine solche Tarnung handelte es sich nach Einsch\u00e4tzung der Beh\u00f6rden beispielsweise bei einem mutma\u00dflichen russischen Spion, der seit Oktober in Norwegen in Untersuchungshaft sitzt. Er hatte sich als brasilianischer Forscher ausgegeben.<\/p>\n<p>Als Reaktion auf den Beginn des russischen Angriffskriegs auf die Ukraine am 24. Februar hatten europ\u00e4ische Staaten russische Agenten ausgewiesen. Die Bundesregierung erkl\u00e4rte Anfang April 40 Angeh\u00f6rige der russischen Botschaft in Berlin zu unerw\u00fcnschten Personen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die russische Armee hat erneut Luftangriffe auf Kiew geflogen, Drohnentr\u00fcmmer verletzten einen jungen Mann. Und: Pr\u00e4sident Selenskyj nennt den Gegner \u00bberb\u00e4rmliche Terroristen\u00ab. Die wichtigsten Entwicklungen. Was in den vergangenen Stunden<\/p>\n","protected":false},"author":1,"featured_media":17283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17282"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17283"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}