{"id":17232,"date":"2022-12-31T04:07:20","date_gmt":"2022-12-31T01:07:20","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/donald-trump-die-wichtigsten-erkenntnisse-zu-den-steuererklarungen-des-ex-us-prasidenten\/"},"modified":"2022-12-31T04:07:20","modified_gmt":"2022-12-31T01:07:20","slug":"donald-trump-die-wichtigsten-erkenntnisse-zu-den-steuererklarungen-des-ex-us-prasidenten","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/donald-trump-die-wichtigsten-erkenntnisse-zu-den-steuererklarungen-des-ex-us-prasidenten\/","title":{"rendered":"Donald Trump: Die wichtigsten Erkenntnisse zu den Steuererkl\u00e4rungen des Ex-US-Pr\u00e4sidenten"},"content":{"rendered":"<p class=\"caps\">Massive Verluste, merkw\u00fcrdige Zahlen, mysteri\u00f6se Auslandskonten: Der US-Kongress hat Steuerkl\u00e4rungen von Donald Trump ver\u00f6ffentlicht. Sie zerst\u00f6ren sein Image vom erfolgreichen Gesch\u00e4ftsmann. Die wichtigsten Erkenntnisse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Massive Verluste, merkw\u00fcrdige Zahlen, mysteri\u00f6se Auslandskonten: Der US-Kongress hat Steuerkl\u00e4rungen von Donald Trump ver\u00f6ffentlicht. Sie zerst\u00f6ren sein Image vom erfolgreichen Gesch\u00e4ftsmann. Die wichtigsten Erkenntnisse.<\/p>\n","protected":false},"author":1,"featured_media":17233,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17232"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17233"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}