{"id":17212,"date":"2022-12-30T07:48:50","date_gmt":"2022-12-30T04:48:50","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-freitag-30-dezember\/"},"modified":"2022-12-30T07:48:50","modified_gmt":"2022-12-30T04:48:50","slug":"news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-freitag-30-dezember","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/news-zum-russland-ukraine-krieg-das-geschah-in-der-nacht-zu-freitag-30-dezember\/","title":{"rendered":"News zum Russland-Ukraine-Krieg: Das geschah in der Nacht zu Freitag (30. Dezember)"},"content":{"rendered":"<p class=\"caps\">Laut ukrainischem Pr\u00e4sidenten gibt es in weiten Teilen des Landes keinen Strom. Belarus will eine Erkl\u00e4rung f\u00fcr Raketenfragmente auf seinem Territorium. Und: Gro\u00dfbritannien schickt Metalldetektoren. Die wichtigsten Entwicklungen.  <\/p>\n<h3><strong>Was in den vergangenen Stunden geschah<\/strong><\/h3>\n<p>Die massiven russischen Raketenangriffe auf die Energieinfrastruktur der Ukraine haben nach Angaben Kiews zu Stromausf\u00e4llen in weiten Teilen des Landes gef\u00fchrt. \u00bbHeute Abend kommt es in den meisten Regionen der Ukraine zu Stromausf\u00e4llen\u00ab, sagte der ukrainische Pr\u00e4sident Wolodymyr Selenskyj am Donnerstagabend in einer Videoansprache. \u00bbBesonders schwierig\u00ab sei die Lage unter anderem in der Region Kiew und in der Hauptstadt selbst, in der westlichen Region Lwiw sowie in den Regionen Odessa und Cherson im S\u00fcden des Landes.<\/p>\n<p>Von insgesamt 69 abgefeuerten Geschossen habe die ukrainische Luftabwehr aber 54 abgefangen, erkl\u00e4rte der Oberbefehlshaber der ukrainischen Streitkr\u00e4fte, Walery Saluschny. In der ostukrainischen Gro\u00dfstadt Charkiw starb nach Angaben des Regionalgouverneurs mindestens ein Mensch bei dem Beschuss.<\/p>\n<p>Die ukrainische Luftwaffe teilte mit: \u00bbDer Feind greift die Ukraine an mehreren Fronten an, mit Marschflugk\u00f6rpern, die von Flugzeugen und Schiffen aus abgefeuert werden\u00ab. Oberbefehlshaber Saluschny sprach im Onlinedienst Telegram von \u00bbRaketenterror gegen die friedliche Bev\u00f6lkerung\u00ab.<\/p>\n<p>Neben dem Toten in Charkiw wurden mehrere Menschen bei den j\u00fcngsten russischen Luftangriffen verletzt, wie ukrainische Vertreter mitteilten. In der Hauptstadt Kiew wurden drei Menschen durch den Beschuss verletzt, wie B\u00fcrgermeister Vitali Klitschko auf Telegram berichtete. Unter anderem wurden demnach im Osten Kiews zwei H\u00e4user von Fragmenten abgeschossener Raketen getroffen. 40 Prozent der Einwohner der Hauptstadt seien von Stromausf\u00e4llen betroffen.<\/p>\n<p>In der s\u00fcdukrainischen Stadt Cherson wurden nach Angaben des Pr\u00e4sidialb\u00fcros zwei Menschen beim Angriff auf eine medizinische Einrichtung verletzt. \u00dcber der s\u00fcdlichen Region Odessa wurden nach offiziellen Angaben 21 Raketen abgefangen, in der Hafenstadt selbst wurden demnach die Energieinfrastruktur besch\u00e4digt und der Strom vorsorglich abgeschaltet.<\/p>\n<p>Der russische Beschuss reichte diesmal bis weit in den Westen der Ukraine. Raketen schlugen in der l\u00e4ndlichen Karpaten-Region Iwano-Frankiwsk ein, die fast 1000 Kilometer von Russland entfernt ist und nahe der Grenze zu Rum\u00e4nien und der Slowakei liegt. In der westlichen Stadt Lwiw waren nach mehreren Explosionen nach Angaben des dortigen B\u00fcrgermeisters sogar 90 Prozent der Haushalte ohne Strom. Es drohte dort ein Ausfall der Wasserversorgung.<\/p>\n<p>Die ukrainischen Streitkr\u00e4fte haben nach eigener Darstellung russische St\u00fctzpunkte in der Umgebung der Industrie- und Hafenstadt Berdjansk im S\u00fcdosten des Landes angegriffen. Dabei seien rund 50 russische Soldaten \u00bbliquidiert\u00ab worden, teilte der Generalstab in Kiew mit. Die Angaben konnten nicht unabh\u00e4ngig \u00fcberpr\u00fcft werden.<\/p>\n<p>Die Milit\u00e4rs in Kiew machten keine Angaben dazu, mit welchen Waffensystemen Berdjansk angegriffen wurde. Die Stadt am Asowschen Meer liegt knapp 100 Kilometer hinter den aktuellen Frontlinien.<\/p>\n<h3><strong>Das sagt Kiew<\/strong><\/h3>\n<p>Russland r\u00fcckt mit jedem weiteren Raketenangriff gegen die Ukraine nach Ansicht von Pr\u00e4sident Selenskyj n\u00e4her an ein Internationales Tribunal heran. \u00bbMit jedem solchen Raketenangriff treibt sich Russland nur noch tiefer in eine Sackgasse\u00ab, sagte Selenskyj am Donnerstagabend in seiner t\u00e4glichen Videoansprache.<\/p>\n<p>Der \u00bbStatus des gr\u00f6\u00dften Terroristen der Welt\u00ab werde sich noch lange auf Russland und seine B\u00fcrger auswirken. \u00bbUnd jede Rakete best\u00e4tigt nur, dass das alles mit einem Tribunal enden muss, genau so wird es sein\u00ab, sagte Selenskyj. In seinen Unterredungen mit ausl\u00e4ndischen Staats- und Regierungschefs versucht der ukrainische Staatschef, deren Unterst\u00fctzung f\u00fcr einen Internationalen Strafgerichtshof nach dem Vorbild des N\u00fcrnberger Tribunals zu gewinnen, vor dem sich Politiker und Milit\u00e4rs aus Moskau f\u00fcr den Angriffskrieg gegen die Ukraine verantworten sollen.<\/p>\n<p>Nach dem Fund einer Rakete auf dem Staatsgebiet von Belarus hat das ukrainische Verteidigungsministerium seine Mitarbeit an den Untersuchungen des Vorfalls angeboten. In einer am Donnerstagabend ver\u00f6ffentlichten Erkl\u00e4rung des Ministeriums in Kiew hei\u00dft es, dass die Beh\u00f6rde zu einer \u00bbobjektiven Untersuchung des Vorfalls\u00ab bereit sei. Staatsmedien in der belarussischen Hauptstadt Minsk hatten berichtet, dass eine vom Flugabwehrsystem S-300 abgeschossene Rakete am Donnerstagvormittag auf belarussisches Staatsgebiet gefallen sei.<\/p>\n<p>Das Verteidigungsministerium in Kiew wies darauf hin, dass die Ukraine am Donnerstag von einer Welle russischer Marschflugk\u00f6rper angegriffen worden sei. \u00bbDaher ist auch eine Provokation von Seiten des Terroristen-Staats Russland nicht auszuschlie\u00dfen, der eine Flugroute seiner Marschflugk\u00f6rper so ausgew\u00e4hlt hat, um ihren Abschuss im Luftraum \u00fcber Belarus zu provozieren\u00ab, hie\u00df es. Das w\u00e4re ein \u00e4hnlicher Vorfall wie im November, als polnisches Gebiet getroffen wurde.<\/p>\n<p>Der belarussische Langzeit-Machthaber Alexander Lukaschenko war \u00fcber den Vorfall informiert worden. Das belarussische Au\u00dfenministerium berief den ukrainischen Botschafter ein und \u00e4u\u00dferte \u00bbscharfen Protest\u00ab. Der Vorfall m\u00fcsse umgehend untersucht werden, da derartige Vorkommnisse \u00bbkatastrophale Folgen\u00ab haben k\u00f6nnten und sich nicht wiederholen d\u00fcrften, erkl\u00e4rte das Ministerium.<\/p>\n<p>Belarus ist nicht direkt an Kampfhandlungen in der Ukraine beteiligt. Allerdings hat Lukaschenko russischen Truppen die Milit\u00e4rbasen in dem Land f\u00fcr Angriffe auf die Ukraine \u00fcberlassen.<\/p>\n<p>In der Ukraine sind die Sorgen gro\u00df, dass Russland von Belarus aus einen neuen Angriff starten k\u00f6nnte. Ein solcher Fund einer Rakete k\u00f6nnte von Belarus und Russland als Vorwand genutzt werden, um von dort aus wieder aktiv zu werden.<\/p>\n<h3><strong>Das sagt Moskau<\/strong><\/h3>\n<p>In Moskau weihte am Donnerstag Pr\u00e4sident Wladimir Putin in einer Zeremonie per Videobotschaft mehrere neue Kriegsschiffe ein, darunter ein U-Boot, das Atomraketen abfeuern kann. Putin k\u00fcndigte die Produktion weiterer Schiffe an und r\u00fchmte die F\u00e4higkeiten der russischen Marine.<\/p>\n<p>Die russische Armee gilt trotz der Modernisierung, die sich Putin als Priorit\u00e4t gesetzt hat, noch immer als teils unzureichend ausger\u00fcstet und schlecht organisiert. Bei ihrer Invasion der Ukraine hat sie eine Reihe von R\u00fcckschl\u00e4gen hinnehmen m\u00fcssen.<\/p>\n<h3><strong>Humanit\u00e4re Lage<\/strong><\/h3>\n<p>Seit Kriegsbeginn in der Ukraine werden nach Angaben der ukrainischen Pr\u00e4sidentenberaterin Alona Verbytska Tausende Soldaten und Zivilisten vermisst. \u00bbRussland hat aktuell 3392 ukrainische Kriegsgefangene best\u00e4tigt, aber in der Ukraine gelten derzeit 15.000 Menschen als vermisst, darunter viele Zivilisten\u00ab, sagte sie dem Redaktionsnetzwerk Deutschland (Freitag). Das Schicksal dieser Menschen sei v\u00f6llig ungewiss, sagte Verbytska, die sich als Ombudsfrau f\u00fcr die Rechte ukrainischer Soldaten engagiert.<\/p>\n<p>\u00bbWir wissen nicht, was mit ihnen geschehen ist\u00ab, sagte sie. \u00bbBefinden sie sich auch in russischer Kriegsgefangenschaft, sind sie aus russisch besetzten Gebieten verschleppt oder wom\u00f6glich l\u00e4ngst umgebracht worden?\u00ab Diese Ungewissheit sei vor allem f\u00fcr die Angeh\u00f6rigen schrecklich.<\/p>\n<p>Ukrainische Beh\u00f6rden haben wiederholt darauf hingewiesen, dass ganze Familien und auch Kinder aus den besetzten Gebieten nach Russland verschleppt w\u00fcrden.<\/p>\n<h3><strong>Internationale Reaktionen<\/strong><\/h3>\n<p>Gro\u00dfbritannien stellt der Ukraine mehr als 1000 Metalldetektoren und 100 Sets zur Entsch\u00e4rfung von Bomben zur Verf\u00fcgung. \u00bbRusslands Einsatz von Landminen und der Angriff auf die zivile Infrastruktur unterstreichen die schockierende Grausamkeit von Putins Invasion\u00ab, sagt der britische Verteidigungsminister Ben Wallace einer Erkl\u00e4rung zufolge.             Die von der deutschen Firma Vallon hergestellten Metalldetektoren und Sets helfen der Ukraine, \u00bbLand und Geb\u00e4ude sicher zu r\u00e4umen, w\u00e4hrend sie ihr rechtm\u00e4\u00dfiges Territorium zur\u00fcckerobern\u00ab. Au\u00dferdem k\u00fcndigte Wallace an, dass Gro\u00dfbritannien der Ukraine auch im Jahr 2023 2,3 Milliarden Pfund an Milit\u00e4rhilfe zur Verf\u00fcgung stellen werde.<\/p>\n<p>US-Pr\u00e4sident Joe Biden hat das neue Haushaltsgesetz seiner Regierung unterzeichnet, das unter anderem milliardenschwere Hilfen f\u00fcr die Ukraine vorsieht. Mit seiner Unterschrift setzte Biden am Donnerstagabend (Ortszeit) den von beiden Kongresskammern gebilligten Etat mit einem Volumen von 1,7 Billionen US-Dollar in Kraft. F\u00fcr die Unterst\u00fctzung der Ukraine sind rund 45 Milliarden US-Dollar vorgesehen.<\/p>\n<p>Nato-Generalsekret\u00e4r Jens Stoltenberg hat Deutschland und die anderen B\u00fcndnisstaaten zu weiteren Waffenlieferungen an die Ukraine aufgerufen. \u00bbEs mag paradox klingen, aber milit\u00e4rische Unterst\u00fctzung f\u00fcr die Ukraine ist der schnellste Weg zum Frieden\u00ab, sagte der Norweger der Nachrichtenagentur dpa. Hintergrund sei, dass Russlands Pr\u00e4sident Wladimir Putin davon \u00fcberzeugt werden m\u00fcsse, dass er sein Ziel, die Kontrolle \u00fcber die Ukraine zu \u00fcbernehmen, nicht erreichen werde. Dann k\u00f6nne es eine friedliche Verhandlungsl\u00f6sung geben, die ein \u00dcberleben der Ukraine als unabh\u00e4ngiger demokratischer Staat gew\u00e4hrleiste.<\/p>\n<h3><strong>Was heute passiert<\/strong><\/h3>\n<ul>\n<li>\n<p>Der russische Pr\u00e4sident Putin und Chinas Staatschef Xi Jinping wollen am Freitag ein Gespr\u00e4ch per Videoleitung f\u00fchren. Nach Angaben des Kremls wird sich der Meinungsaustausch um \u00bbdie wichtigsten regionalen Probleme\u00ab drehen \u2013 sowohl solche, \u00bbdie Russland n\u00e4her liegen\u00ab, als auch solche, \u00bbdie China n\u00e4her liegen\u00ab. Angesichts der internationalen Verurteilung der russischen Offensive in der Ukraine und der westlichen Sanktionen will Putin seine Beziehungen zu Peking verst\u00e4rken und die wirtschaftliche Zusammenarbeit ankurbeln. Die beiden L\u00e4nder verstehen sich als geopolitisches Gegengewicht zu den USA und ihren Verb\u00fcndeten.<\/p>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Laut ukrainischem Pr\u00e4sidenten gibt es in weiten Teilen des Landes keinen Strom. Belarus will eine Erkl\u00e4rung f\u00fcr Raketenfragmente auf seinem Territorium. Und: Gro\u00dfbritannien schickt Metalldetektoren. Die wichtigsten Entwicklungen. Was in<\/p>\n","protected":false},"author":1,"featured_media":17213,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17212"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17213"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}