{"id":17184,"date":"2022-12-29T02:46:14","date_gmt":"2022-12-28T23:46:14","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gaspreise-warum-private-haushalte-noch-lange-teuer-fur-ihr-gas-bezahlen-mussen\/"},"modified":"2022-12-29T02:46:14","modified_gmt":"2022-12-28T23:46:14","slug":"gaspreise-warum-private-haushalte-noch-lange-teuer-fur-ihr-gas-bezahlen-mussen","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gaspreise-warum-private-haushalte-noch-lange-teuer-fur-ihr-gas-bezahlen-mussen\/","title":{"rendered":"Gaspreise: Warum private Haushalte noch lange teuer f\u00fcr ihr Gas bezahlen m\u00fcssen"},"content":{"rendered":"<p class=\"caps\">Erdgas verbilligt sich rapide an Europas Energieb\u00f6rsen, Wirtschaftsminister Robert Habeck stellt noch g\u00fcnstigere Preise in Aussicht. Doch Endverbraucher sollten nicht zu fr\u00fch auf Tarifsenkungen hoffen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erdgas verbilligt sich rapide an Europas Energieb\u00f6rsen, Wirtschaftsminister Robert Habeck stellt noch g\u00fcnstigere Preise in Aussicht. Doch Endverbraucher sollten nicht zu fr\u00fch auf Tarifsenkungen hoffen.<\/p>\n","protected":false},"author":1,"featured_media":17185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17184"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17184\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17185"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}