{"id":17176,"date":"2022-12-28T18:17:07","date_gmt":"2022-12-28T15:17:07","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/kapitolausschuss-wie-eine-26-jahrige-zur-kronzeugin-gegen-donald-trump-wurde\/"},"modified":"2022-12-28T18:17:07","modified_gmt":"2022-12-28T15:17:07","slug":"kapitolausschuss-wie-eine-26-jahrige-zur-kronzeugin-gegen-donald-trump-wurde","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/kapitolausschuss-wie-eine-26-jahrige-zur-kronzeugin-gegen-donald-trump-wurde\/","title":{"rendered":"Kapitolausschuss: Wie eine 26-J\u00e4hrige zur Kronzeugin gegen Donald Trump wurde"},"content":{"rendered":"<p class=\"caps\">Ihr Auftritt war einer der dramatischsten bei den Anh\u00f6rungen zum Sturm auf das US-Kapitol: Cassidy Hutchinson hat Donald Trump schwer belastet. Wie es dazu kam, erinnert an einen Mafiafilm.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ihr Auftritt war einer der dramatischsten bei den Anh\u00f6rungen zum Sturm auf das US-Kapitol: Cassidy Hutchinson hat Donald Trump schwer belastet. Wie es dazu kam, erinnert an einen Mafiafilm.<\/p>\n","protected":false},"author":1,"featured_media":17177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17176"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17177"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}