{"id":17170,"date":"2022-12-28T11:57:45","date_gmt":"2022-12-28T08:57:45","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/einkommensrechner-wie-arm-und-reich-in-deutschland-heizen-und-wo-sie-stehen\/"},"modified":"2022-12-28T11:57:45","modified_gmt":"2022-12-28T08:57:45","slug":"einkommensrechner-wie-arm-und-reich-in-deutschland-heizen-und-wo-sie-stehen","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/einkommensrechner-wie-arm-und-reich-in-deutschland-heizen-und-wo-sie-stehen\/","title":{"rendered":"Einkommensrechner: Wie Arm und Reich in Deutschland heizen \u2013 und wo Sie stehen"},"content":{"rendered":"<p class=\"caps\">Die teure Energie trifft nicht alle gleich hart. Je nach Art der Heizung zeigen sich erhebliche Einkommensunterschiede. Mit einer interaktiven Grafik finden Sie heraus, wie Sie selbst im Vergleich zu anderen abschneiden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die teure Energie trifft nicht alle gleich hart. Je nach Art der Heizung zeigen sich erhebliche Einkommensunterschiede. Mit einer interaktiven Grafik finden Sie heraus, wie Sie selbst im Vergleich zu<\/p>\n","protected":false},"author":1,"featured_media":17171,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17170"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17171"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}