{"id":17134,"date":"2022-12-26T21:56:43","date_gmt":"2022-12-26T18:56:43","guid":{"rendered":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gerechtigkeit-in-der-energiekrise-das-ist-eine-scheindiskussion-um-die-reichen-zu-schonen\/"},"modified":"2022-12-26T21:56:43","modified_gmt":"2022-12-26T18:56:43","slug":"gerechtigkeit-in-der-energiekrise-das-ist-eine-scheindiskussion-um-die-reichen-zu-schonen","status":"publish","type":"post","link":"https:\/\/onlinetranslators.de\/news\/nachrichten\/gerechtigkeit-in-der-energiekrise-das-ist-eine-scheindiskussion-um-die-reichen-zu-schonen\/","title":{"rendered":"Gerechtigkeit in der Energiekrise: \u00bbDas ist eine Scheindiskussion, um die Reichen zu schonen\u00ab"},"content":{"rendered":"<p class=\"caps\">Wer soll die Lasten der Energiekrise tragen? Die Wirtschaftsweise Monika Schnitzer und der liberale \u00d6konom Stefan Kooths streiten \u00fcber h\u00f6here Steuern f\u00fcr Spitzenverdiener und den neuen Schuldenstaat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer soll die Lasten der Energiekrise tragen? Die Wirtschaftsweise Monika Schnitzer und der liberale \u00d6konom Stefan Kooths streiten \u00fcber h\u00f6here Steuern f\u00fcr Spitzenverdiener und den neuen Schuldenstaat.<\/p>\n","protected":false},"author":1,"featured_media":17135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-17134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/comments?post=17134"}],"version-history":[{"count":0,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/posts\/17134\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media\/17135"}],"wp:attachment":[{"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/media?parent=17134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/categories?post=17134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onlinetranslators.de\/news\/wp-json\/wp\/v2\/tags?post=17134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}